{"id":2703,"date":"2021-02-12T15:06:40","date_gmt":"2021-02-12T15:06:40","guid":{"rendered":"https:\/\/www.rentila.com.br\/blog\/?p=2703"},"modified":"2024-11-18T12:24:22","modified_gmt":"2024-11-18T12:24:22","slug":"o-que-resolver-antes-de-um-novo-inquilino-se-mudar","status":"publish","type":"post","link":"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/","title":{"rendered":"O que resolver antes de um novo inquilino se mudar"},"content":{"rendered":"<div><img decoding=\"async\" class=\"alignleft size-full wp-image-516\" title=\"newspaper\" src=\"https:\/\/www.rentila.com.br\/assets\/img\/blog\/blog_accounting.png\" alt=\"10 Issues To Address Before A New Tenant Moves In\" width=\"100%\" height=\"\"><\/div>\n<div class=\"sommaire\">\n<div class=\"phase-content__flag phase-1\">Resumo<\/div>\n<ol>\n \t<li><a href=\"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/#1\">Revise a propriedade<\/a><\/li>\n \t<li><a href=\"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/#2\">Repare o que esteja desgastado<\/a><\/li>\n \t<li><a href=\"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/#3\">Resolva os problemas potenciais<\/a><\/li>\n \t<li><a href=\"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/#4\">Troque as fechaduras<\/a><\/li>\n \t<li><a href=\"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/#5\">Recolha o dep\u00f3sito<\/a><\/li>\n \t<li><a href=\"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/#6\">Revise o check-list<\/a><\/li>\n \t<li><a href=\"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/#7\">Defina expectativas<\/a><\/li>\n \t<li><a href=\"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/#8\">Em tempos de Covid<\/a><\/li>\n \t<li><a href=\"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/#9\">Coisas para lembrar<\/a><\/li>\n<\/ol>\n<\/div>\n<p class=\"lead\">Se voc\u00ea est\u00e1 prestes a passar por uma troca de inquilinos, n\u00e3o se desespere. Contanto que voc\u00ea se organize, o que h\u00e1 para resolver antes de um novo inquilino se mudar pode ser mais simples do que voc\u00ea pensa.<\/p>\n<p class=\"lead\">A chave \u00e9 fazer uma lista, agendar cada tarefa e come\u00e7ar cedo &#8211; muitos reparos ou itens de manuten\u00e7\u00e3o podem ser feitos antes que seu locat\u00e1rio atual se mude e o novo chegue.<\/p>\n<!--more-->\n<h2 id=\"1\">Revise a propriedade<\/h2>\nAntes de seus \u00faltimos inquilinos desocuparem a propriedade, voc\u00ea deve ter conduzido uma inspe\u00e7\u00e3o de aluguel antes da mudan\u00e7a, s\u00f3 assim voc\u00ea ter\u00e1 uma boa no\u00e7\u00e3o do que \u00e9 preciso resolver antes de um novo inquilino se mudar.\n\nVoc\u00ea deve sempre revisar a propriedade novamente ap\u00f3s a mudan\u00e7a para que possa avaliar com precis\u00e3o se ocorreu algum dano durante a mudan\u00e7a.\n<h2 id=\"2\">Repare o que esteja desgastado<\/h2>\nAinda que a propriedade n\u00e3o tenha sido danificada de alguma forma, voc\u00ea ainda ter\u00e1 um pouco de trabalho a fazer. Os novos locat\u00e1rios n\u00e3o devem herdar o desgaste normal dos \u00faltimos locat\u00e1rios.\n\nIsso significa retocar a pintura onde for necess\u00e1rio, substituir todas as l\u00e2mpadas piscantes e assim por diante. Claro, voc\u00ea tamb\u00e9m deve limpar a casa ou o apartamento completamente.\n\nSe voc\u00ea faz isso pessoalmente ou contrata um servi\u00e7o \u00e9 com voc\u00ea, mas a propriedade deve ser limpa e higienizada entre a troca de locat\u00e1rios.\n<h2 id=\"3\">Resolva os problemas potenciais<\/h2>\nAntes de um inquilino se mudar, voc\u00ea deve garantir que todos os servi\u00e7os p\u00fablicos estejam funcionando. Verifique se o aquecimento e o ar condicionado funcionam corretamente em todos os c\u00f4modos.\n\nConfirme se n\u00e3o h\u00e1 vazamentos no encanamento ou nos ralos de movimento lento. Teste cada tomada para garantir que esteja funcionando.\n\nAgora tamb\u00e9m \u00e9 um \u00f3timo momento para fazer melhorias que est\u00e3o escondidas em sua lista de tarefas. Claro, voc\u00ea j\u00e1 alugou o im\u00f3vel, e o inquilino n\u00e3o estar\u00e1 necessariamente esperando as atualiza\u00e7\u00f5es, mas que maneira excelente de surpreend\u00ea-lo e incentiv\u00e1-lo a renovar o contrato.\n<h2 id=\"4\">Troque as fechaduras<\/h2>\nEntre as coisas mais importantes a se resolver antes de um novo inquilino se mudar, est\u00e1 a troca das fechaduras de todas as portas. Isso ajuda a garantir a seguran\u00e7a do inquilino e proteg\u00ea-lo contra qualquer incidente.\n\nVoc\u00ea pode recodificar seu bloqueio atual ou considerar a adi\u00e7\u00e3o de uma atualiza\u00e7\u00e3o com entrada sem chave.\n\nUm c\u00f3digo simples permitir\u00e1 que quando seus inquilinos entrem no im\u00f3vel possam escolher sua senha pessoal para uma troca r\u00e1pida e gratuita de fechaduras.\n\nSe voc\u00ea ainda n\u00e3o trabalha com entrada por c\u00f3digos, \u00e9 bom considerar. Os inquilinos tamb\u00e9m ir\u00e3o apreciar a conveni\u00eancia de entrar em sua casa sem uma chave.\n<h2 id=\"5\">Recolha o dep\u00f3sito<\/h2>\nAntes de dar as chaves de seu im\u00f3vel aos inquilinos, voc\u00ea precisar\u00e1 garantir um dep\u00f3sito de seguran\u00e7a.\n\nVoc\u00ea deveria ter recolhido, junto com o aluguel do primeiro m\u00eas, quando eles assinaram o contrato. No entanto, se voc\u00ea n\u00e3o fez isso, agora \u00e9 a hora de faz\u00ea-lo.\n<h2 id=\"6\">Revise o check-list<\/h2>\nNo dia da mudan\u00e7a real, voc\u00ea deve caminhar pela propriedade sozinho para anotar a apar\u00eancia de tudo. Observe a condi\u00e7\u00e3o de cada quarto e at\u00e9 mesmo tire fotos.\n\nEm seguida, fa\u00e7a o mesmo passo a passo com o inquilino, pedindo-lhe que assine e date esta lista de verifica\u00e7\u00e3o. Isso \u00e9 crucial, pois permite comparar a condi\u00e7\u00e3o da propriedade quando o inquilino se muda com a forma da propriedade quando ele se muda.\n\nEmbora possa parecer desnecess\u00e1rio percorrer a propriedade e revisar a lista de verifica\u00e7\u00e3o do im\u00f3vel alugado duas vezes, \u00e9 importante.\n\nVoc\u00ea vai querer dar uma olhada por conta pr\u00f3pria para garantir que tudo esteja de acordo com seus padr\u00f5es. Ent\u00e3o, voc\u00ea saber\u00e1 que tudo est\u00e1 em ordem quando voc\u00ea e o inquilino analisarem a lista de verifica\u00e7\u00e3o juntos.\n<h2 id=\"7\">Defina expectativas<\/h2>\nO ideal \u00e9 que voc\u00ea tenha um contrato de aluguel eletr\u00f4nico, de modo que seu inquilino tenha acesso ao contrato, \u00e0s regras e aos procedimentos em todos os momentos.\n\nTamb\u00e9m \u00e9 \u00fatil lembrar os novos inquilinos no dia da mudan\u00e7a por e-mail sobre as expectativas, incluindo quando e como entrar em contato com voc\u00ea.\n\nVoc\u00ea deve fornecer um n\u00famero de telefone onde possa ser encontrado e dizer claramente que trata sua propriedade como um neg\u00f3cio, portanto, que o inquilino pode ligar para voc\u00ea apenas durante o hor\u00e1rio comercial, a menos que haja uma emerg\u00eancia real.\n<h2 id=\"8\">Em tempos de Covid<\/h2>\nAo preparar um aluguel para novos inquilinos durante o surto do coronav\u00edrus, os propriet\u00e1rios precisam tomar precau\u00e7\u00f5es extras para garantir sua seguran\u00e7a pessoal, bem como cumprir as ordens estaduais e locais de ficar em casa. Os propriet\u00e1rios devem:\n<ul>\n \t<li>verificar se a prepara\u00e7\u00e3o de um aluguel n\u00e3o est\u00e1 violando as ordens estaduais ou locais de estadia em casa<\/li>\n \t<li>usar uma m\u00e1scara ou outro equipamento de prote\u00e7\u00e3o para evitar a transmiss\u00e3o do v\u00edrus<\/li>\n \t<li>tomar medidas extras para desinfetar os espa\u00e7os<\/li>\n \t<li>ajustar suas pol\u00edticas e procedimentos de exibi\u00e7\u00e3o para acomodar as diretrizes de distanciamento social<\/li>\n \t<li>ser extremamente diligente ao documentar todos os procedimentos comerciais, pois o estresse e outras complica\u00e7\u00f5es relacionadas ao surto podem fazer com que voc\u00ea se desvie (mesmo que n\u00e3o intencionalmente) de seus procedimentos normais<\/li>\n<\/ul>\n<h2 id=\"9\">Coisas para lembrar<\/h2>\nCertifique-se sempre de que tudo seja legal e seguro para seus inquilinos antes de eles se mudarem.\n<ul>\n \t<li>Isso significa garantir que a propriedade esteja limpa<\/li>\n \t<li>Possui as certifica\u00e7\u00f5es necess\u00e1rias para g\u00e1s, eletricidade e mon\u00f3xido de carbono<\/li>\n \t<li>Possui fechaduras seguras rec\u00e9m trocadas<\/li>\n \t<li>Certifique-se de ter um novo contrato de loca\u00e7\u00e3o em vigor, verifique as condi\u00e7\u00f5es do im\u00f3vel<\/li>\n \t<li>E que seus inquilinos conhe\u00e7am suas responsabilidades de manuten\u00e7\u00e3o, bem como seus dados de contato em caso de emerg\u00eancia<\/li>\n<\/ul>\n<!-- \/wp:post-content -->","protected":false},"excerpt":{"rendered":"<p>Resumo Revise a propriedade Repare o que esteja desgastado Resolva os problemas potenciais Troque as fechaduras Recolha o dep\u00f3sito Revise o check-list Defina expectativas Em tempos de Covid Coisas para lembrar Se voc\u00ea est\u00e1 prestes a passar por uma troca de inquilinos, n\u00e3o se desespere. Contanto que voc\u00ea se organize, o que h\u00e1 para resolver [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2703","post","type-post","status-publish","format-standard","hentry","category-dicas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O que resolver antes de um novo inquilino se mudar -<\/title>\n<meta name=\"description\" content=\"Contanto que voc\u00ea se organize, o que h\u00e1 para resolver antes de um novo inquilino se mudar pode ser mais simples do que voc\u00ea pensa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que resolver antes de um novo inquilino se mudar -\" \/>\n<meta property=\"og:description\" content=\"Contanto que voc\u00ea se organize, o que h\u00e1 para resolver antes de um novo inquilino se mudar pode ser mais simples do que voc\u00ea pensa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de gest\u00e3o de im\u00f3veis para propriet\u00e1rios\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Rentila-Espa%c3%b1a-234200993854422\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-12T15:06:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-18T12:24:22+00:00\" \/>\n<meta name=\"author\" content=\"Rentila\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rentila\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\\\/\"},\"author\":{\"name\":\"Rentila\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/69e85f4958e187e6ebfa75f658753a65\"},\"headline\":\"O que resolver antes de um novo inquilino se mudar\",\"datePublished\":\"2021-02-12T15:06:40+00:00\",\"dateModified\":\"2024-11-18T12:24:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\\\/\"},\"wordCount\":1048,\"image\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rentila.com.br\\\/assets\\\/img\\\/blog\\\/blog_accounting.png\",\"articleSection\":[\"Dicas\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\\\/\",\"url\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\\\/\",\"name\":\"O que resolver antes de um novo inquilino se mudar -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rentila.com.br\\\/assets\\\/img\\\/blog\\\/blog_accounting.png\",\"datePublished\":\"2021-02-12T15:06:40+00:00\",\"dateModified\":\"2024-11-18T12:24:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/69e85f4958e187e6ebfa75f658753a65\"},\"description\":\"Contanto que voc\u00ea se organize, o que h\u00e1 para resolver antes de um novo inquilino se mudar pode ser mais simples do que voc\u00ea pensa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rentila.com.br\\\/assets\\\/img\\\/blog\\\/blog_accounting.png\",\"contentUrl\":\"https:\\\/\\\/www.rentila.com.br\\\/assets\\\/img\\\/blog\\\/blog_accounting.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que resolver antes de um novo inquilino se mudar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/\",\"name\":\"Blog de gest\u00e3o de im\u00f3veis para propriet\u00e1rios\",\"description\":\"Conselhos pr\u00e1ticos, not\u00edcias imobili\u00e1rias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/69e85f4958e187e6ebfa75f658753a65\",\"name\":\"Rentila\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4fca21133a60c87d700e0dacc408e758b6e572296ec467d947953283975eea8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4fca21133a60c87d700e0dacc408e758b6e572296ec467d947953283975eea8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4fca21133a60c87d700e0dacc408e758b6e572296ec467d947953283975eea8?s=96&d=mm&r=g\",\"caption\":\"Rentila\"},\"url\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/author\\\/roumen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que resolver antes de um novo inquilino se mudar -","description":"Contanto que voc\u00ea se organize, o que h\u00e1 para resolver antes de um novo inquilino se mudar pode ser mais simples do que voc\u00ea pensa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/","og_locale":"pt_BR","og_type":"article","og_title":"O que resolver antes de um novo inquilino se mudar -","og_description":"Contanto que voc\u00ea se organize, o que h\u00e1 para resolver antes de um novo inquilino se mudar pode ser mais simples do que voc\u00ea pensa.","og_url":"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/","og_site_name":"Blog de gest\u00e3o de im\u00f3veis para propriet\u00e1rios","article_publisher":"https:\/\/www.facebook.com\/Rentila-Espa%c3%b1a-234200993854422\/","article_published_time":"2021-02-12T15:06:40+00:00","article_modified_time":"2024-11-18T12:24:22+00:00","author":"Rentila","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Rentila","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/#article","isPartOf":{"@id":"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/"},"author":{"name":"Rentila","@id":"https:\/\/www.rentila.com.br\/blog\/#\/schema\/person\/69e85f4958e187e6ebfa75f658753a65"},"headline":"O que resolver antes de um novo inquilino se mudar","datePublished":"2021-02-12T15:06:40+00:00","dateModified":"2024-11-18T12:24:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/"},"wordCount":1048,"image":{"@id":"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rentila.com.br\/assets\/img\/blog\/blog_accounting.png","articleSection":["Dicas"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/","url":"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/","name":"O que resolver antes de um novo inquilino se mudar -","isPartOf":{"@id":"https:\/\/www.rentila.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/#primaryimage"},"image":{"@id":"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rentila.com.br\/assets\/img\/blog\/blog_accounting.png","datePublished":"2021-02-12T15:06:40+00:00","dateModified":"2024-11-18T12:24:22+00:00","author":{"@id":"https:\/\/www.rentila.com.br\/blog\/#\/schema\/person\/69e85f4958e187e6ebfa75f658753a65"},"description":"Contanto que voc\u00ea se organize, o que h\u00e1 para resolver antes de um novo inquilino se mudar pode ser mais simples do que voc\u00ea pensa.","breadcrumb":{"@id":"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/#primaryimage","url":"https:\/\/www.rentila.com.br\/assets\/img\/blog\/blog_accounting.png","contentUrl":"https:\/\/www.rentila.com.br\/assets\/img\/blog\/blog_accounting.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rentila.com.br\/blog\/o-que-resolver-antes-de-um-novo-inquilino-se-mudar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rentila.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"O que resolver antes de um novo inquilino se mudar"}]},{"@type":"WebSite","@id":"https:\/\/www.rentila.com.br\/blog\/#website","url":"https:\/\/www.rentila.com.br\/blog\/","name":"Blog de gest\u00e3o de im\u00f3veis para propriet\u00e1rios","description":"Conselhos pr\u00e1ticos, not\u00edcias imobili\u00e1rias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rentila.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.rentila.com.br\/blog\/#\/schema\/person\/69e85f4958e187e6ebfa75f658753a65","name":"Rentila","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/c4fca21133a60c87d700e0dacc408e758b6e572296ec467d947953283975eea8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c4fca21133a60c87d700e0dacc408e758b6e572296ec467d947953283975eea8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c4fca21133a60c87d700e0dacc408e758b6e572296ec467d947953283975eea8?s=96&d=mm&r=g","caption":"Rentila"},"url":"https:\/\/www.rentila.com.br\/blog\/author\/roumen\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/posts\/2703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2703"}],"version-history":[{"count":8,"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/posts\/2703\/revisions"}],"predecessor-version":[{"id":2751,"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/posts\/2703\/revisions\/2751"}],"wp:attachment":[{"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}