{"id":2433,"date":"2020-10-16T14:57:07","date_gmt":"2020-10-16T14:57:07","guid":{"rendered":"https:\/\/www.rentila.com.br\/blog\/?p=2433"},"modified":"2024-11-18T12:24:49","modified_gmt":"2024-11-18T12:24:49","slug":"guia-co-living-para-o-proprietario","status":"publish","type":"post","link":"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/","title":{"rendered":"Guia co-living para o propriet\u00e1rio"},"content":{"rendered":"<div><img decoding=\"async\" class=\"alignleft size-full wp-image-516\" title=\"newspaper\" src=\"https:\/\/www.rentila.com.br\/assets\/img\/blog\/blog_tenants_1.png\" alt=\"Guia co-living para o propriet\u00e1rio\" width=\"100%\" height=\"\"><\/div>\n<div class=\"sommaire\">\n<div class=\"phase-content__flag phase-1\">Resumo<\/div>\n<ol>\n \t<li><a href=\"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/#1\">O que \u00e9 co-living?<\/a><\/li>\n \t<li><a href=\"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/#2\">Propriedades adequadas para co-living<\/a><\/li>\n \t<li><a href=\"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/#3\">Legisla\u00e7\u00e3o de co-living para o propriet\u00e1rio<\/a><\/li>\n \t<li><a href=\"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/#4\">Montando o ambiente do co-living<\/a><\/li>\n \t<li><a href=\"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/#5\">Atrair os inquilinos certos<\/a><\/li>\n \t<li><a href=\"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/#6\">Guia co-living de valores<\/a><\/li>\n<\/ol>\n<\/div>\n<p class=\"lead\">Para saber o que \u00e9 \u201cco-habita\u00e7\u00e3o\u201d, criamos um guia co-living para o propriet\u00e1rio entender como funciona esse estilo de vida compartilhada.<\/p>\n<p class=\"lead\">Co-living combina indiv\u00edduos com interesses semelhantes, quartos privados, muito espa\u00e7o compartilhado, muitas comodidades e alugu\u00e9is de curto prazo.<\/p>\n<p class=\"lead\">O que antes era uma op\u00e7\u00e3o de moradia reservada para o dormit\u00f3rio da faculdade agora est\u00e1 se tornando mais popular entre os profissionais de todo o pa\u00eds.&nbsp;<\/p>\n<p class=\"lead\">\u00c9 uma maneira de driblar os alugu\u00e9is cada vez mais altos em mercados quentes, que acaba tamb\u00e9m se tornando outra boa op\u00e7\u00e3o para propriet\u00e1rios.<\/p>\n<!--more-->\n<h2 id=\"1\">O que \u00e9 co-living?<\/h2>\nEmbora a acomoda\u00e7\u00e3o compartilhada sempre tenha existido, o co-living, termo em ingl\u00eas que quer dizer compartilhar morada, \u00e9 uma abordagem considerada mais interessante para alugar para v\u00e1rios inquilinos.\n\nOs co-living foram inspirados pelas ideias que impulsionam os ambientes de co-working, esses espa\u00e7os de trabalho compartido com salas de reuni\u00e3o dispon\u00edveis e toda a sorte de extras, como caf\u00e9, ch\u00e1 e produtos de higiene.\n\nOs espa\u00e7os de co-living s\u00e3o geralmente projetados especificamente para oferecer \u00e1reas de dormit\u00f3rio privativas e silenciosas, com elegantes espa\u00e7os de plano aberto para socializa\u00e7\u00e3o.\n<h2 id=\"2\">Propriedades adequadas para co-living<\/h2>\nOs espa\u00e7os de conviv\u00eancia s\u00e3o especialmente populares entre os jovens e nas \u00e1reas metropolitanas.\n\nOs conceitos de co-living para estudantes j\u00e1 existem h\u00e1 algum tempo, mas o crescimento mais recente nas convers\u00f5es industriais tamb\u00e9m abriu o mercado para espa\u00e7os sofisticados procurados normalmente por jovens profissionais.\n\nA demanda por esses espa\u00e7os se reflete no surgimento de empreendimentos de marca.\n\nEssas propriedades de luxo concentram-se em servi\u00e7os agregados como academias, bares e outras instala\u00e7\u00f5es que complementam o design dos apartamentos &#8211; vendendo um estilo de vida e n\u00e3o apenas um espa\u00e7o.\n<h2 id=\"3\">Legisla\u00e7\u00e3o de co-living para o propriet\u00e1rio<\/h2>\nPode haver, no entanto, algumas barreiras \u00e0 entrada. Em alguns pa\u00edses, a convers\u00e3o de propriedades \u00e9 o primeiro obst\u00e1culo: na Alemanha, por exemplo, o zoneamento de propriedades para uso residencial pode levar tempo, dinheiro e papelada.\n\nEm outros pa\u00edses, pode haver requisitos rigorosos para ter um espa\u00e7o de conviv\u00eancia aprovado pelas autoridades, incluindo a aquisi\u00e7\u00e3o de certificados de seguran\u00e7a e mostrando que h\u00e1 espa\u00e7o e instala\u00e7\u00f5es suficientes para o n\u00famero pretendido de inquilinos.\n\nNo Brasil, a modalidade de morada compartilhada ainda \u00e9 algo novo, que vem sendo estudado para sua melhor compreens\u00e3o na Lei do Inquilinato.&nbsp;\n\nTanto no caso de um aluguel normal quanto no de aluguel de co-living, o que n\u00e3o muda \u00e9 o fato de o inquilino ser o respons\u00e1vel pelo pagamento da casa, quarto ou at\u00e9 mesmo uma cama.\n\nAl\u00e9m, \u00e9 claro, das demais obriga\u00e7\u00f5es com a quita\u00e7\u00e3o de IPTU, \u00e1gua, luz e outros que constem no contrato de loca\u00e7\u00e3o.\n\nPara garantir que voc\u00ea est\u00e1 do lado certo da lei, este guia co-living para o propriet\u00e1rio sugere que voc\u00ea verifique os sites do governo, consulte advogados ou um bom agente imobili\u00e1rio da sua cidade.\n<h2 id=\"4\">Montando o ambiente do co-living<\/h2>\nEncontrar o inquilino perfeito pode ser dif\u00edcil, e isso \u00e9 ainda mais verdadeiro no caso de espa\u00e7os de conviv\u00eancia, onde voc\u00ea estar\u00e1 procurando v\u00e1rios ocupantes.\n\nComece elaborando um conceito de co-living s\u00f3lido, baseado nas amenidades locais, para encontrar o seu mercado-alvo.\n\nAs liga\u00e7\u00f5es de transporte p\u00fablico s\u00e3o ideais para os novos moradores? Voc\u00ea est\u00e1 perto da universidade e, portanto, tem como alvo alunos de doutorado ou pesquisadores em in\u00edcio de carreira? Existe uma cena cultural ou culin\u00e1ria pr\u00f3spera?\n\nEm seguida, considere como voc\u00ea vai organizar e mobiliar sua propriedade para atrair seu mercado.\n\nVoc\u00ea precisar\u00e1 encontrar um equil\u00edbrio entre as \u00e1reas privadas, como quartos e banheiros (garantindo que haja o suficiente de cada um), e as \u00e1reas sociais, como o jardim, terra\u00e7o ou at\u00e9 mesmo um bar.\n\nVoc\u00ea pode querer fazer de uma cozinha grande e bem equipada, que certamente vai se tornar a pe\u00e7a central de seu projeto: j\u00e1 que esta ser\u00e1 uma \u00e1rea chave para seus inquilinos se encontrarem e se misturarem.\n\nPor isso \u00e9 importante que seja um lugar atraente para passar o tempo, al\u00e9m de ter espa\u00e7o suficiente e equipamentos para todos.\n\nPor \u00faltimo, preste aten\u00e7\u00e3o aos detalhes: de banda larga super r\u00e1pida a eletrodom\u00e9sticos de alta qualidade, eles far\u00e3o uma diferen\u00e7a real no estilo de vida dos seus inquilinos.\n<h2 id=\"5\">Atrair os inquilinos certos<\/h2>\n\u00c9 vital procurar um agente imobili\u00e1rio local que conhe\u00e7a o seu mercado. Eles devem ser capazes de localizar propriedades que seriam apropriadas para convers\u00e3o em co-living em termos de localiza\u00e7\u00e3o, tamanho, estilo e retorno sobre o investimento.\n\nEles tamb\u00e9m podem acessar sua rede para ajud\u00e1-lo a encontrar inquilinos com vis\u00e3o de futuro que apreciar\u00e3o o estilo de vida.\n\nFinalmente, voc\u00ea deve considerar cuidadosamente o seu pre\u00e7o. Os inquilinos que vivem juntos esperam uma boa rela\u00e7\u00e3o custo-benef\u00edcio, mas n\u00e3o est\u00e3o procurando por uma divis\u00e3o de casa barata.\n\nEnt\u00e3o trabalhe com seu corretor de im\u00f3veis para garantir que voc\u00ea encontre uma equa\u00e7\u00e3o favor\u00e1vel entre o que voc\u00ea quer gastar e os frutos que v\u00e3o te render.\n<h2 id=\"6\">Guia co-living de valores<\/h2>\nEm uma cidade onde quartos privados custam a partir de R$ 1.200 e est\u00fadios privados custam a partir de R$ 1.640, as comodidades incluem camas, sof\u00e1s, toalhas, len\u00e7\u00f3is, HDTVs e alto-falantes, uma cozinha de chef, uma combina\u00e7\u00e3o de lavanderia \/ fliperama e um est\u00fadio de ioga.\n\nPode haver tamb\u00e9m, por exemplo, um concierge em tempo integral e uma equipe de limpeza.\n\nAmbos servi\u00e7os poderiam ser oferecidos por uma \u201ctaxa de comodidade\u201d adicional, que arcariam com servi\u00e7os p\u00fablicos, wifi, cabo e limpeza mensal.&nbsp;\n\nA dica de ouro que vem neste guia co-living para o propriet\u00e1rio que deseje criar o co-living dos sonhos \u00e9 disponibilizar alguns quartos para aluguel por noite, e assim oferecer uma experi\u00eancia de teste antes de alugar.\n\n<!-- \/wp:post-content -->","protected":false},"excerpt":{"rendered":"<p>Resumo O que \u00e9 co-living? Propriedades adequadas para co-living Legisla\u00e7\u00e3o de co-living para o propriet\u00e1rio Montando o ambiente do co-living Atrair os inquilinos certos Guia co-living de valores Para saber o que \u00e9 \u201cco-habita\u00e7\u00e3o\u201d, criamos um guia co-living para o propriet\u00e1rio entender como funciona esse estilo de vida compartilhada. Co-living combina indiv\u00edduos com interesses semelhantes, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2433","post","type-post","status-publish","format-standard","hentry","category-dicas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guia co-living para o propriet\u00e1rio<\/title>\n<meta name=\"description\" content=\"Para saber o que \u00e9 \u201cco-habita\u00e7\u00e3o\u201d, criamos um guia co-living para o propriet\u00e1rio entender como funciona esse estilo de vida compartilhada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guia co-living para o propriet\u00e1rio\" \/>\n<meta property=\"og:description\" content=\"Para saber o que \u00e9 \u201cco-habita\u00e7\u00e3o\u201d, criamos um guia co-living para o propriet\u00e1rio entender como funciona esse estilo de vida compartilhada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de gest\u00e3o de im\u00f3veis para propriet\u00e1rios\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Rentila-Espa%c3%b1a-234200993854422\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-16T14:57:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-18T12:24:49+00:00\" \/>\n<meta name=\"author\" content=\"Rentila\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rentila\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/guia-co-living-para-o-proprietario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/guia-co-living-para-o-proprietario\\\/\"},\"author\":{\"name\":\"Rentila\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/69e85f4958e187e6ebfa75f658753a65\"},\"headline\":\"Guia co-living para o propriet\u00e1rio\",\"datePublished\":\"2020-10-16T14:57:07+00:00\",\"dateModified\":\"2024-11-18T12:24:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/guia-co-living-para-o-proprietario\\\/\"},\"wordCount\":1056,\"image\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/guia-co-living-para-o-proprietario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rentila.com.br\\\/assets\\\/img\\\/blog\\\/blog_tenants_1.png\",\"articleSection\":[\"Dicas\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/guia-co-living-para-o-proprietario\\\/\",\"url\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/guia-co-living-para-o-proprietario\\\/\",\"name\":\"Guia co-living para o propriet\u00e1rio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/guia-co-living-para-o-proprietario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/guia-co-living-para-o-proprietario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rentila.com.br\\\/assets\\\/img\\\/blog\\\/blog_tenants_1.png\",\"datePublished\":\"2020-10-16T14:57:07+00:00\",\"dateModified\":\"2024-11-18T12:24:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/69e85f4958e187e6ebfa75f658753a65\"},\"description\":\"Para saber o que \u00e9 \u201cco-habita\u00e7\u00e3o\u201d, criamos um guia co-living para o propriet\u00e1rio entender como funciona esse estilo de vida compartilhada.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/guia-co-living-para-o-proprietario\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/guia-co-living-para-o-proprietario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/guia-co-living-para-o-proprietario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rentila.com.br\\\/assets\\\/img\\\/blog\\\/blog_tenants_1.png\",\"contentUrl\":\"https:\\\/\\\/www.rentila.com.br\\\/assets\\\/img\\\/blog\\\/blog_tenants_1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/guia-co-living-para-o-proprietario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guia co-living para o propriet\u00e1rio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/\",\"name\":\"Blog de gest\u00e3o de im\u00f3veis para propriet\u00e1rios\",\"description\":\"Conselhos pr\u00e1ticos, not\u00edcias imobili\u00e1rias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/69e85f4958e187e6ebfa75f658753a65\",\"name\":\"Rentila\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4fca21133a60c87d700e0dacc408e758b6e572296ec467d947953283975eea8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4fca21133a60c87d700e0dacc408e758b6e572296ec467d947953283975eea8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4fca21133a60c87d700e0dacc408e758b6e572296ec467d947953283975eea8?s=96&d=mm&r=g\",\"caption\":\"Rentila\"},\"url\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/author\\\/roumen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guia co-living para o propriet\u00e1rio","description":"Para saber o que \u00e9 \u201cco-habita\u00e7\u00e3o\u201d, criamos um guia co-living para o propriet\u00e1rio entender como funciona esse estilo de vida compartilhada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/","og_locale":"pt_BR","og_type":"article","og_title":"Guia co-living para o propriet\u00e1rio","og_description":"Para saber o que \u00e9 \u201cco-habita\u00e7\u00e3o\u201d, criamos um guia co-living para o propriet\u00e1rio entender como funciona esse estilo de vida compartilhada.","og_url":"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/","og_site_name":"Blog de gest\u00e3o de im\u00f3veis para propriet\u00e1rios","article_publisher":"https:\/\/www.facebook.com\/Rentila-Espa%c3%b1a-234200993854422\/","article_published_time":"2020-10-16T14:57:07+00:00","article_modified_time":"2024-11-18T12:24:49+00:00","author":"Rentila","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Rentila","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/#article","isPartOf":{"@id":"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/"},"author":{"name":"Rentila","@id":"https:\/\/www.rentila.com.br\/blog\/#\/schema\/person\/69e85f4958e187e6ebfa75f658753a65"},"headline":"Guia co-living para o propriet\u00e1rio","datePublished":"2020-10-16T14:57:07+00:00","dateModified":"2024-11-18T12:24:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/"},"wordCount":1056,"image":{"@id":"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rentila.com.br\/assets\/img\/blog\/blog_tenants_1.png","articleSection":["Dicas"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/","url":"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/","name":"Guia co-living para o propriet\u00e1rio","isPartOf":{"@id":"https:\/\/www.rentila.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/#primaryimage"},"image":{"@id":"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rentila.com.br\/assets\/img\/blog\/blog_tenants_1.png","datePublished":"2020-10-16T14:57:07+00:00","dateModified":"2024-11-18T12:24:49+00:00","author":{"@id":"https:\/\/www.rentila.com.br\/blog\/#\/schema\/person\/69e85f4958e187e6ebfa75f658753a65"},"description":"Para saber o que \u00e9 \u201cco-habita\u00e7\u00e3o\u201d, criamos um guia co-living para o propriet\u00e1rio entender como funciona esse estilo de vida compartilhada.","breadcrumb":{"@id":"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/#primaryimage","url":"https:\/\/www.rentila.com.br\/assets\/img\/blog\/blog_tenants_1.png","contentUrl":"https:\/\/www.rentila.com.br\/assets\/img\/blog\/blog_tenants_1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rentila.com.br\/blog\/guia-co-living-para-o-proprietario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rentila.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Guia co-living para o propriet\u00e1rio"}]},{"@type":"WebSite","@id":"https:\/\/www.rentila.com.br\/blog\/#website","url":"https:\/\/www.rentila.com.br\/blog\/","name":"Blog de gest\u00e3o de im\u00f3veis para propriet\u00e1rios","description":"Conselhos pr\u00e1ticos, not\u00edcias imobili\u00e1rias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rentila.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.rentila.com.br\/blog\/#\/schema\/person\/69e85f4958e187e6ebfa75f658753a65","name":"Rentila","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/c4fca21133a60c87d700e0dacc408e758b6e572296ec467d947953283975eea8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c4fca21133a60c87d700e0dacc408e758b6e572296ec467d947953283975eea8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c4fca21133a60c87d700e0dacc408e758b6e572296ec467d947953283975eea8?s=96&d=mm&r=g","caption":"Rentila"},"url":"https:\/\/www.rentila.com.br\/blog\/author\/roumen\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/posts\/2433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2433"}],"version-history":[{"count":18,"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/posts\/2433\/revisions"}],"predecessor-version":[{"id":2479,"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/posts\/2433\/revisions\/2479"}],"wp:attachment":[{"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}