{"id":1979,"date":"2020-06-22T16:51:21","date_gmt":"2020-06-22T16:51:21","guid":{"rendered":"https:\/\/www.rentila.com.br\/blog\/?p=1979"},"modified":"2020-06-23T19:17:10","modified_gmt":"2020-06-23T19:17:10","slug":"o-que-o-proprietario-pode-tirar-do-deposito-caucao","status":"publish","type":"post","link":"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/","title":{"rendered":"O que o propriet\u00e1rio pode tirar do dep\u00f3sito cau\u00e7\u00e3o?"},"content":{"rendered":"\n<div><img decoding=\"async\" class=\"alignleft size-full wp-image-516\" title=\"newspaper\" src=\"https:\/\/www.rentila.com.br\/assets\/img\/blog\/blog_advice_2.png\" alt=\"Como renovar e decorar seu im\u00f3vel antes de alugar\" width=\"100%\" height=\"\"><\/div>\n<div class=\"sommaire\">\n<div class=\"phase-content__flag phase-1\">Sum\u00e1rio<\/div>\n<ol>\n<li><a href=\"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/\">Aluguel n\u00e3o pago<\/a><\/li>\n<li><a href=\"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/\">Danos graves \u00e0 propriedade<\/a><\/li>\n<li><a href=\"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/\">Itens perdidos ou quebrados<\/a><\/li>\n<li><a href=\"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/\">Limpeza<\/a><\/li>\n<li><a href=\"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/\">Manuten\u00e7\u00e3o geral<\/a><\/li>\n<li><a href=\"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/\">Danos causados \u200b\u200bpor animais de estima\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/\">Redecora\u00e7\u00e3o ruim<\/a><\/li>\n<li><a href=\"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/\">Quando os inquilinos podem abrir uma disputa pelo dep\u00f3sito?<\/a><\/li>\n<li><a href=\"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/\">Como fazer uma reivindica\u00e7\u00e3o de dep\u00f3sito<\/a><\/li>\n<li><a href=\"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/\">Para o inquilino lembrar<\/a><\/li>\n<\/ol>\n<\/div>\n<p class=\"lead\">N\u00e3o existe uma regra r\u00edgida quando os inquilinos perguntam: &#8220;O que o propriet\u00e1rio pode tirar do dep\u00f3sito cau\u00e7\u00e3o?&#8221;, Pois isso varia de caso a caso.<\/p>\n<p class=\"lead\">No entanto, existem alguns motivos comuns pelos quais os dep\u00f3sitos n\u00e3o s\u00e3o devolvidos.<\/p>\n<p class=\"lead\">Ap\u00f3s a sa\u00edda do inquilino, os propriet\u00e1rios podem fazer dedu\u00e7\u00f5es de dep\u00f3sito pelos seguintes motivos:<\/p>\n<!--more-->\n<h2><span style=\"font-size: inherit;\">Aluguel n\u00e3o pago<\/h2>\n<p>Existem in\u00fameras raz\u00f5es pelas quais os inquilinos podem n\u00e3o conseguir pagar o aluguel.<\/p>\n<p>No entanto, embora algumas circunst\u00e2ncias estejam fora de controle, o aluguel perdido ou retido \u00e9 uma raz\u00e3o justific\u00e1vel que pode autorizar o propriet\u00e1rio a tirar do dep\u00f3sito cau\u00e7\u00e3o.<\/p>\n<p>Muitos propriet\u00e1rios preferem deduzir dinheiro do dep\u00f3sito, em vez de atender ao inquilino com um aviso de despejo.<\/p>\n<p>Se seu inquilino deve mais do que o valor do dep\u00f3sito, voc\u00ea pode entrar com uma a\u00e7\u00e3o legal, e um tribunal pode decretar que pague o valor total. <\/p>\n<p>Isso implicar\u00e1 em honor\u00e1rios legais pr\u00f3prios, portanto, voc\u00ea precisa pensar se isso faz sentido financeiramente.<\/p>\n<h2>Danos graves \u00e0 propriedade<\/h2>\n<p>Seja na propriedade em si, como janelas quebradas ou m\u00f3veis quebrados, danificar a propriedade contradiz os termos do contrato de loca\u00e7\u00e3o.<\/p>\n<p>Portanto, os propriet\u00e1rios podem deduzir a quantia apropriada do dep\u00f3sito. Imprud\u00eancia \u00e9 algo a ser levado a s\u00e9rio!<\/p>\n<h2>Itens perdidos ou quebrados<\/h2>\n<p>Uma das principais raz\u00f5es para os propriet\u00e1rios n\u00e3o devolverem os dep\u00f3sitos \u00e9 a falta dos itens que constavam originalmente no im\u00f3vel. E o custo destes pode ser deduzido no final da loca\u00e7\u00e3o!<\/p>\n<p>O invent\u00e1rio definir\u00e1 quais itens foram inclu\u00eddos na propriedade e suas condi\u00e7\u00f5es. Portanto, no para a garantia do propriet\u00e1rio, \u00e9 essencial um invent\u00e1rio detalhado.<\/p>\n<h2>Limpeza<\/h2>\n<p>No mundo das disputas de dep\u00f3sito de aluguel, a limpeza pode ser uma grande fonte de desacordo entre propriet\u00e1rios e inquilinos, principalmente porque todos temos defini\u00e7\u00f5es diferentes do que \u00e9 &#8220;limpo&#8221;.<\/p>\n<p>Por exemplo, se foi negociado no contrato de loca\u00e7\u00e3o que o inquilino pagaria por um tapete profissional limpo depois de manter animais de estima\u00e7\u00e3o na propriedade, isso deve ser mantido.<\/p>\n<p>Se n\u00e3o o fizerem, o propriet\u00e1rio pode tirar do dep\u00f3sito. Para um propriet\u00e1rio, a limpeza \u00e9 de responsabilidade do inquilino.<\/p>\n<h2>Manuten\u00e7\u00e3o geral<\/h2>\n<p>A manuten\u00e7\u00e3o geral pode ser dif\u00edcil porque \u00e9 um termo vago. Por\u00e9m, o uso indevido pode resultar em uma dedu\u00e7\u00e3o de dep\u00f3sito. <\/p>\n<p>Por exemplo, se algum equipamento tiver sido deliberadamente negligenciado, o propriet\u00e1rio ter\u00e1 que pagar para repar\u00e1-lo antes do in\u00edcio do pr\u00f3ximo aluguel.<\/p>\n<h2>Danos causados \u200b\u200bpor animais de estima\u00e7\u00e3o<\/h2>\n<p>Propriet\u00e1rios e animais de estima\u00e7\u00e3o t\u00eam um relacionamento tenso. No entanto, como 44% dos domic\u00edlios brasileiros possui um animal de estima\u00e7\u00e3o, os propriet\u00e1rios tiveram que se adaptar a esta realidade.<\/p>\n<p>Antes do in\u00edcio da loca\u00e7\u00e3o, aqueles com animais de estima\u00e7\u00e3o geralmente concordam em pagar um dep\u00f3sito mais alto ou o custo de uma limpeza profissional. Mas isso n\u00e3o torna aceit\u00e1vel qualquer dano causado pelos animais.<\/p>\n<h2>Redecora\u00e7\u00e3o ruim<\/h2>\n<p>Se um inquilino decide redecorar a propriedade sem antes perguntar, isso pode violar o contrato de loca\u00e7\u00e3o. Como resultado, voc\u00ea poder\u00e1 deduzir dinheiro do dep\u00f3sito para recuperar a sala de volta \u00e0 sua condi\u00e7\u00e3o anterior.<\/p>\n<p>Como alternativa, se voc\u00ea permitir que um inquilino redecore, mas ele fizer um mau trabalho, tamb\u00e9m poder\u00e1 solicitar custos para uma redecora\u00e7\u00e3o.<\/p>\n<h2>Quando os inquilinos podem abrir uma disputa pelo dep\u00f3sito?<\/h2>\n<p>Os inquilinos t\u00eam muitas responsabilidades, como acompanhar o pagamento do aluguel e cuidar da propriedade. E ainda assim est\u00e3o sempre se perguntando &#8220;meu locador pode reter o meu dep\u00f3sito?&#8221; A resposta \u00e9 sim, mas dentro do razo\u00e1vel.<\/p>\n<p>Como mencionado anteriormente, o desgaste razo\u00e1vel n\u00e3o \u00e9 um motivo para reter o dinheiro dos inquilinos.<\/p>\n<p>A defini\u00e7\u00e3o de desgaste normal \u00e9 dif\u00edcil, por isso \u00e9 essencial considerar o pr\u00f3prio arrendamento, como a quantidade de inquilinos e o tempo de ocupa\u00e7\u00e3o.<\/p>\n<p>Para os propriet\u00e1rios, o que \u00e9 considerado desgaste normal pode ser uma \u00e1rea cinzenta. Portanto, voc\u00ea precisa justificar qualquer reivindica\u00e7\u00e3o de dep\u00f3sito feita.&nbsp;<\/p>\n<p>Sua propriedade permanecer\u00e1 em uso por um certo per\u00edodo de tempo. Portanto, embora n\u00e3o haja regras para o que \u00e9 &#8220;razoavelmente aceit\u00e1vel&#8221;, voc\u00ea n\u00e3o pode esperar que ela esteja como nova ao final do contrato.<\/p>\n<h2><strong>Como fazer uma reivindica\u00e7\u00e3o de dep\u00f3sito<\/strong><\/h2>\n<p>Se voc\u00ea estiver fazendo uma reivindica\u00e7\u00e3o, escreva para o inquilino e explique exatamente o motivo. <\/p>\n<p>Os inquilinos precisam entender seus motivos. As disputas de loca\u00e7\u00e3o precisam ser claramente comunicadas entre as duas partes.<\/p>\n<p>Se eles concordarem com o seu racioc\u00ednio, voc\u00ea n\u00e3o precisar\u00e1 passar por um servi\u00e7o de disputa. No entanto, \u00e9 prov\u00e1vel que discordem.<\/p>\n<p>Um servi\u00e7o de disputa ser\u00e1 fornecido gratuitamente pelo esquema de dep\u00f3sito de loca\u00e7\u00e3o que voc\u00ea usou. Muitas vezes, pode ser dif\u00edcil encontrar uma resolu\u00e7\u00e3o de disputas, no entanto, o uso de um servi\u00e7o profissional garante que seja justo.<\/p>\n<h2>Check list para o inquilino<\/h2>\n<ul style=\"list-style-type: disc;\">\n<li>Fa\u00e7a um invent\u00e1rio &#8211; Pode parecer uma tarefa cansativa e bastante pedante, mas documentar a condi\u00e7\u00e3o da propriedade pode fornecer evid\u00eancias vitais.<\/li>\n<li style=\"font-weight: 400;\">Pagar contas pendentes e alugar.<\/li>\n<li style=\"font-weight: 400;\">Fa\u00e7a uma prova documentada das leituras do medidor antes de sair.<\/li>\n<li style=\"font-weight: 400;\">Cobrir pequenos reparos, como l\u00e2mpadas quebradas e buracos nas paredes.<\/li>\n<li style=\"font-weight: 400;\">Fa\u00e7a voc\u00ea mesmo um contrato de loca\u00e7\u00e3o ou chame um profissional.<\/li>\n<li style=\"font-weight: 400;\">Certifique-se de que o jardim tenha o padr\u00e3o de quando voc\u00ea se mudou.<\/li>\n<li style=\"font-weight: 400;\">Desodorize o tabaco e os odores dos animais.<\/li>\n<li style=\"font-weight: 400;\">Limpe todo o lixo e tudo o que \u00e9 seu.<\/li>\n<li style=\"font-weight: 400;\">O propriet\u00e1rio tem dez dias para devolver seu dep\u00f3sito ou entrar em contato com voc\u00ea.<\/li>\n<li style=\"font-weight: 400;\">Entenda o que \u00e9 desgaste razo\u00e1vel e o que \u00e9 dano.<\/li>\n<li style=\"font-weight: 400;\">No caso de uma disputa, permanecer calmo e razo\u00e1vel \u00e9 sempre o melhor caminho.<\/li>\n<li style=\"font-weight: 400;\">Forne\u00e7a todas as suas evid\u00eancias de maneira organizada. A decis\u00e3o final n\u00e3o poder\u00e1 ser contestada.<\/li>\n<\/ul>\n\n\n<div class=\"rpbt_shortcode\">\n<h3>Related Posts<\/h3>\n<ul>\n\t\t\t\t\t\n\t\t\t<li>\n\t\t\t\t<a href=\"https:\/\/www.rentila.com.br\/blog\/contratos-de-fianca-para-proprietarios-protecao-riscos-e-clausulas-essenciais\/\">Contratos de fian\u00e7a para propriet\u00e1rios: prote\u00e7\u00e3o, riscos e cl\u00e1usulas essenciais<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\n\t\t\t<li>\n\t\t\t\t<a href=\"https:\/\/www.rentila.com.br\/blog\/causas-mais-comuns-de-estresse-para-os-proprietarios\/\">Causas mais comuns de estresse para os propriet\u00e1rios<\/a>\n\t\t\t<\/li>\n\t\t\t<\/ul>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Sum\u00e1rio Aluguel n\u00e3o pago Danos graves \u00e0 propriedade Itens perdidos ou quebrados Limpeza Manuten\u00e7\u00e3o geral Danos causados \u200b\u200bpor animais de estima\u00e7\u00e3o Redecora\u00e7\u00e3o ruim Quando os inquilinos podem abrir uma disputa pelo dep\u00f3sito? Como fazer uma reivindica\u00e7\u00e3o de dep\u00f3sito Para o inquilino lembrar N\u00e3o existe uma regra r\u00edgida quando os inquilinos perguntam: &#8220;O que o propriet\u00e1rio [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[103,105],"class_list":["post-1979","post","type-post","status-publish","format-standard","hentry","category-basics","tag-deposito-caucao","tag-proprietario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O que o propriet\u00e1rio pode tirar do dep\u00f3sito cau\u00e7\u00e3o?<\/title>\n<meta name=\"description\" content=\"N\u00e3o existe uma regra r\u00edgida quando os inquilinos perguntam: &quot;O que o propriet\u00e1rio pode tirar do dep\u00f3sito cau\u00e7\u00e3o?&quot;, Pois isso varia de caso a caso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que o propriet\u00e1rio pode tirar do dep\u00f3sito cau\u00e7\u00e3o?\" \/>\n<meta property=\"og:description\" content=\"N\u00e3o existe uma regra r\u00edgida quando os inquilinos perguntam: &quot;O que o propriet\u00e1rio pode tirar do dep\u00f3sito cau\u00e7\u00e3o?&quot;, Pois isso varia de caso a caso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de gest\u00e3o de im\u00f3veis para propriet\u00e1rios\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Rentila-Espa%c3%b1a-234200993854422\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-22T16:51:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-23T19:17:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rentila.com.br\/assets\/img\/blog\/furniture_1400.png\" \/>\n<meta name=\"author\" content=\"Rentila\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rentila\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\\\/\"},\"author\":{\"name\":\"Rentila\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/69e85f4958e187e6ebfa75f658753a65\"},\"headline\":\"O que o propriet\u00e1rio pode tirar do dep\u00f3sito cau\u00e7\u00e3o?\",\"datePublished\":\"2020-06-22T16:51:21+00:00\",\"dateModified\":\"2020-06-23T19:17:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\\\/\"},\"wordCount\":1094,\"image\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rentila.com.br\\\/assets\\\/img\\\/blog\\\/blog_advice_2.png\",\"keywords\":[\"Dep\u00f3sito cau\u00e7\u00e3o\",\"Propriet\u00e1rio\"],\"articleSection\":[\"Os b\u00e1sicos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\\\/\",\"url\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\\\/\",\"name\":\"O que o propriet\u00e1rio pode tirar do dep\u00f3sito cau\u00e7\u00e3o?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rentila.com.br\\\/assets\\\/img\\\/blog\\\/blog_advice_2.png\",\"datePublished\":\"2020-06-22T16:51:21+00:00\",\"dateModified\":\"2020-06-23T19:17:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/69e85f4958e187e6ebfa75f658753a65\"},\"description\":\"N\u00e3o existe uma regra r\u00edgida quando os inquilinos perguntam: \\\"O que o propriet\u00e1rio pode tirar do dep\u00f3sito cau\u00e7\u00e3o?\\\", Pois isso varia de caso a caso.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rentila.com.br\\\/assets\\\/img\\\/blog\\\/blog_advice_2.png\",\"contentUrl\":\"https:\\\/\\\/www.rentila.com.br\\\/assets\\\/img\\\/blog\\\/blog_advice_2.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que o propriet\u00e1rio pode tirar do dep\u00f3sito cau\u00e7\u00e3o?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/\",\"name\":\"Blog de gest\u00e3o de im\u00f3veis para propriet\u00e1rios\",\"description\":\"Conselhos pr\u00e1ticos, not\u00edcias imobili\u00e1rias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/69e85f4958e187e6ebfa75f658753a65\",\"name\":\"Rentila\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4fca21133a60c87d700e0dacc408e758b6e572296ec467d947953283975eea8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4fca21133a60c87d700e0dacc408e758b6e572296ec467d947953283975eea8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4fca21133a60c87d700e0dacc408e758b6e572296ec467d947953283975eea8?s=96&d=mm&r=g\",\"caption\":\"Rentila\"},\"url\":\"https:\\\/\\\/www.rentila.com.br\\\/blog\\\/author\\\/roumen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que o propriet\u00e1rio pode tirar do dep\u00f3sito cau\u00e7\u00e3o?","description":"N\u00e3o existe uma regra r\u00edgida quando os inquilinos perguntam: \"O que o propriet\u00e1rio pode tirar do dep\u00f3sito cau\u00e7\u00e3o?\", Pois isso varia de caso a caso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/","og_locale":"pt_BR","og_type":"article","og_title":"O que o propriet\u00e1rio pode tirar do dep\u00f3sito cau\u00e7\u00e3o?","og_description":"N\u00e3o existe uma regra r\u00edgida quando os inquilinos perguntam: \"O que o propriet\u00e1rio pode tirar do dep\u00f3sito cau\u00e7\u00e3o?\", Pois isso varia de caso a caso.","og_url":"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/","og_site_name":"Blog de gest\u00e3o de im\u00f3veis para propriet\u00e1rios","article_publisher":"https:\/\/www.facebook.com\/Rentila-Espa%c3%b1a-234200993854422\/","article_published_time":"2020-06-22T16:51:21+00:00","article_modified_time":"2020-06-23T19:17:10+00:00","og_image":[{"url":"https:\/\/www.rentila.com.br\/assets\/img\/blog\/furniture_1400.png","type":"","width":"","height":""}],"author":"Rentila","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Rentila","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/#article","isPartOf":{"@id":"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/"},"author":{"name":"Rentila","@id":"https:\/\/www.rentila.com.br\/blog\/#\/schema\/person\/69e85f4958e187e6ebfa75f658753a65"},"headline":"O que o propriet\u00e1rio pode tirar do dep\u00f3sito cau\u00e7\u00e3o?","datePublished":"2020-06-22T16:51:21+00:00","dateModified":"2020-06-23T19:17:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/"},"wordCount":1094,"image":{"@id":"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rentila.com.br\/assets\/img\/blog\/blog_advice_2.png","keywords":["Dep\u00f3sito cau\u00e7\u00e3o","Propriet\u00e1rio"],"articleSection":["Os b\u00e1sicos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/","url":"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/","name":"O que o propriet\u00e1rio pode tirar do dep\u00f3sito cau\u00e7\u00e3o?","isPartOf":{"@id":"https:\/\/www.rentila.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/#primaryimage"},"image":{"@id":"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rentila.com.br\/assets\/img\/blog\/blog_advice_2.png","datePublished":"2020-06-22T16:51:21+00:00","dateModified":"2020-06-23T19:17:10+00:00","author":{"@id":"https:\/\/www.rentila.com.br\/blog\/#\/schema\/person\/69e85f4958e187e6ebfa75f658753a65"},"description":"N\u00e3o existe uma regra r\u00edgida quando os inquilinos perguntam: \"O que o propriet\u00e1rio pode tirar do dep\u00f3sito cau\u00e7\u00e3o?\", Pois isso varia de caso a caso.","breadcrumb":{"@id":"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/#primaryimage","url":"https:\/\/www.rentila.com.br\/assets\/img\/blog\/blog_advice_2.png","contentUrl":"https:\/\/www.rentila.com.br\/assets\/img\/blog\/blog_advice_2.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rentila.com.br\/blog\/o-que-o-proprietario-pode-tirar-do-deposito-caucao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rentila.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"O que o propriet\u00e1rio pode tirar do dep\u00f3sito cau\u00e7\u00e3o?"}]},{"@type":"WebSite","@id":"https:\/\/www.rentila.com.br\/blog\/#website","url":"https:\/\/www.rentila.com.br\/blog\/","name":"Blog de gest\u00e3o de im\u00f3veis para propriet\u00e1rios","description":"Conselhos pr\u00e1ticos, not\u00edcias imobili\u00e1rias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rentila.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.rentila.com.br\/blog\/#\/schema\/person\/69e85f4958e187e6ebfa75f658753a65","name":"Rentila","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/c4fca21133a60c87d700e0dacc408e758b6e572296ec467d947953283975eea8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c4fca21133a60c87d700e0dacc408e758b6e572296ec467d947953283975eea8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c4fca21133a60c87d700e0dacc408e758b6e572296ec467d947953283975eea8?s=96&d=mm&r=g","caption":"Rentila"},"url":"https:\/\/www.rentila.com.br\/blog\/author\/roumen\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/posts\/1979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1979"}],"version-history":[{"count":10,"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/posts\/1979\/revisions"}],"predecessor-version":[{"id":2005,"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/posts\/1979\/revisions\/2005"}],"wp:attachment":[{"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rentila.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}